{"id":920501,"date":"2025-07-24T17:25:11","date_gmt":"2025-07-24T20:25:11","guid":{"rendered":"https:\/\/bahiaeconomica.com.br\/wp\/?p=920501"},"modified":"2025-07-24T16:42:03","modified_gmt":"2025-07-24T19:42:03","slug":"governo-do-brasil-regulamenta-politica-nacional-de-cuidados","status":"publish","type":"post","link":"https:\/\/bahiaeconomica.com.br\/wp\/2025\/07\/24\/governo-do-brasil-regulamenta-politica-nacional-de-cuidados\/","title":{"rendered":"GOVERNO DO BRASIL REGULAMENTA POL\u00cdTICA NACIONAL DE CUIDADOS"},"content":{"rendered":"<p>Nesta quinta-feira (24.07) foi publicado o Decreto n\u00ba 12.562, que regulamenta a Pol\u00edtica Nacional de Cuidados, sancionada em dezembro de 2024. A iniciativa representa mais uma etapa no reconhecimento do cuidado como uma necessidade de todas as pessoas, como um direito a ser garantido pelo Estado e como um trabalho essencial para o bem-estar das pessoas, a reprodu\u00e7\u00e3o e a sustenta\u00e7\u00e3o da vida e o funcionamento da sociedade e da economia.<\/p>\n<p>&#8220;O Brasil trabalha em sintonia com v\u00e1rios pa\u00edses e tivemos um debate que come\u00e7ou no primeiro ano do mandato do presidente Lula, em 2023. Depois, a lei que estabelece a Pol\u00edtica Nacional de Cuidados foi aprovada pelo Congresso Nacional e sancionada pelo presidente Lula, em 2024&#8221;, lembrou o titular do MDS, Wellington Dias. &#8220;Agora, \u00e9 a responsabilidade de trabalharmos o plano. Estamos muito contentes porque esse \u00e9 um passo fundamental&#8221;, completou.<\/p>\n<p>O decreto abre caminho para o lan\u00e7amento do Plano Nacional de Cuidados, que ser\u00e1 detalhado em portaria conjunta do MDS, Minist\u00e9rio das Mulheres e Minist\u00e9rio dos Direitos Humanos e da Cidadania. Nesse documento ser\u00e3o apresentadas as a\u00e7\u00f5es e as entregas a serem ofertadas \u00e0 popula\u00e7\u00e3o e o respectivo or\u00e7amento; as metas; os instrumentos de implementa\u00e7\u00e3o; o per\u00edodo de vig\u00eancia; e os \u00f3rg\u00e3os e as entidades respons\u00e1veis pela execu\u00e7\u00e3o das a\u00e7\u00f5es.<\/p>\n<p>&#8220;Agora \u00e9 o momento de avan\u00e7ar na implementa\u00e7\u00e3o das a\u00e7\u00f5es concretas propostas pelos diversos minist\u00e9rios envolvidos na constru\u00e7\u00e3o da Pol\u00edtica Nacional de Cuidados que visam responder a demandas expressas por diversos setores da popula\u00e7\u00e3o&#8221;, disse a secret\u00e1ria Nacional de Cuidados e Fam\u00edlia do MDS, La\u00eds Abramo. &#8220;E tamb\u00e9m de colocar em pr\u00e1tica as estruturas de governan\u00e7a do Plano que envolvem a participa\u00e7\u00e3o de estados, munic\u00edpios e da sociedade civil&#8221;, acrescentou.<\/p>\n<p>O Plano, como instrumento de implementa\u00e7\u00e3o da Pol\u00edtica Nacional de Cuidados, tem como objetivo garantir o direito ao cuidado, por meio de pol\u00edticas p\u00fablicas que fomentem a corresponsabiliza\u00e7\u00e3o social e entre homens e mulheres em rela\u00e7\u00e3o \u00e0 provis\u00e3o de cuidados.<\/p>\n<p>Dados demonstram que at\u00e9 hoje, milh\u00f5es de mulheres e jovens no Brasil, em especial negras e mais pobres, s\u00e3o obrigadas a abandonar seus estudos ou empregos devido \u00e0 falta de apoio para compartilhar as responsabilidades de cuidado.<\/p>\n<p>Segundo a Organiza\u00e7\u00e3o Internacional do Trabalho (OIT), em 2023, 748 milh\u00f5es de pessoas com 15 anos ou mais n\u00e3o participavam na for\u00e7a de trabalho global devido a responsabilidades de cuidados, representando um ter\u00e7o de todas as pessoas em idade ativa fora da for\u00e7a de trabalho. Desse total, 708 milh\u00f5es eram mulheres e 40 milh\u00f5es eram homens.<\/p>\n<p>No Brasil, os dados do IBGE mostram uma realidade semelhante: entre as adolescentes e jovens que n\u00e3o conclu\u00edram o ensino m\u00e9dio no pa\u00eds, um ter\u00e7o parou de estudar ou nunca estudou devido \u00e0 sua necessidade de cuidar da casa, dos filhos e filhas e outros parentes. Essa cifra \u00e9 66% superior para as jovens negras em compara\u00e7\u00e3o com as brancas. Esse \u00e9 tamb\u00e9m o principal motivo pelo qual mais de 80% das m\u00e3es de crian\u00e7as de 0 a 3 anos que est\u00e3o fora do mercado de trabalho n\u00e3o conseguem sequer buscar um emprego ou n\u00e3o poderiam aceitar um emprego caso lhes fosse oferecido.<\/p>\n<p>Foto: Lyon Santos\/ MDS<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nesta quinta-feira (24.07) foi publicado o Decreto n\u00ba 12.562, que regulamenta a Pol\u00edtica Nacional de Cuidados, sancionada em dezembro de 2024. A iniciativa representa mais uma etapa no reconhecimento do cuidado como uma necessidade de todas as pessoas, como um direito a ser garantido pelo Estado e como um trabalho essencial para o bem-estar das [&hellip;]<\/p>\n","protected":false},"author":15,"featured_media":920505,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[21],"tags":[34670],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v20.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>GOVERNO DO BRASIL REGULAMENTA POL\u00cdTICA NACIONAL DE CUIDADOS - Bahia Economica<\/title>\n<meta name=\"description\" content=\"O maior portal de Economia da Bahia Sa\u00fade \/ Educa\u00e7\u00e3o Bahia Economica Nesta quinta-feira (24.07) foi publicado o Decreto n\u00ba 12.562, que regulamenta\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/bahiaeconomica.com.br\/wp\/2025\/07\/24\/governo-do-brasil-regulamenta-politica-nacional-de-cuidados\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"GOVERNO DO BRASIL REGULAMENTA POL\u00cdTICA NACIONAL DE CUIDADOS - Bahia Economica\" \/>\n<meta property=\"og:description\" content=\"O maior portal de Economia da Bahia Sa\u00fade \/ Educa\u00e7\u00e3o Bahia Economica Nesta quinta-feira (24.07) foi publicado o Decreto n\u00ba 12.562, que regulamenta\" \/>\n<meta property=\"og:url\" content=\"https:\/\/bahiaeconomica.com.br\/wp\/2025\/07\/24\/governo-do-brasil-regulamenta-politica-nacional-de-cuidados\/\" \/>\n<meta property=\"og:site_name\" content=\"Bahia Economica\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/bahiaeconomica\" \/>\n<meta property=\"article:published_time\" content=\"2025-07-24T20:25:11+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-24T19:42:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/bahiaeconomica.com.br\/wp\/wp-content\/uploads\/2025\/07\/handler-5.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"768\" \/>\n\t<meta property=\"og:image:height\" content=\"512\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"VICTORIA ISABEL\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"VICTORIA ISABEL\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/bahiaeconomica.com.br\/wp\/2025\/07\/24\/governo-do-brasil-regulamenta-politica-nacional-de-cuidados\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/bahiaeconomica.com.br\/wp\/2025\/07\/24\/governo-do-brasil-regulamenta-politica-nacional-de-cuidados\/\"},\"author\":{\"name\":\"VICTORIA ISABEL\",\"@id\":\"https:\/\/bahiaeconomica.com.br\/wp\/#\/schema\/person\/b719ce0fb1c09f3c7a00d9243ced4a6f\"},\"headline\":\"GOVERNO DO BRASIL REGULAMENTA POL\u00cdTICA NACIONAL DE CUIDADOS\",\"datePublished\":\"2025-07-24T20:25:11+00:00\",\"dateModified\":\"2025-07-24T19:42:03+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/bahiaeconomica.com.br\/wp\/2025\/07\/24\/governo-do-brasil-regulamenta-politica-nacional-de-cuidados\/\"},\"wordCount\":573,\"publisher\":{\"@id\":\"https:\/\/bahiaeconomica.com.br\/wp\/#organization\"},\"keywords\":[\"Pol\u00edtica Nacional de Cuidados\"],\"articleSection\":[\"Sa\u00fade \/ Educa\u00e7\u00e3o\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/bahiaeconomica.com.br\/wp\/2025\/07\/24\/governo-do-brasil-regulamenta-politica-nacional-de-cuidados\/\",\"url\":\"https:\/\/bahiaeconomica.com.br\/wp\/2025\/07\/24\/governo-do-brasil-regulamenta-politica-nacional-de-cuidados\/\",\"name\":\"GOVERNO DO BRASIL REGULAMENTA POL\u00cdTICA NACIONAL DE CUIDADOS - Bahia Economica\",\"isPartOf\":{\"@id\":\"https:\/\/bahiaeconomica.com.br\/wp\/#website\"},\"datePublished\":\"2025-07-24T20:25:11+00:00\",\"dateModified\":\"2025-07-24T19:42:03+00:00\",\"description\":\"O maior portal de Economia da Bahia Sa\u00fade \/ Educa\u00e7\u00e3o Bahia Economica Nesta quinta-feira (24.07) foi publicado o Decreto n\u00ba 12.562, que regulamenta\",\"breadcrumb\":{\"@id\":\"https:\/\/bahiaeconomica.com.br\/wp\/2025\/07\/24\/governo-do-brasil-regulamenta-politica-nacional-de-cuidados\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/bahiaeconomica.com.br\/wp\/2025\/07\/24\/governo-do-brasil-regulamenta-politica-nacional-de-cuidados\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/bahiaeconomica.com.br\/wp\/2025\/07\/24\/governo-do-brasil-regulamenta-politica-nacional-de-cuidados\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/bahiaeconomica.com.br\/wp\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"GOVERNO DO BRASIL REGULAMENTA POL\u00cdTICA NACIONAL DE CUIDADOS\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/bahiaeconomica.com.br\/wp\/#website\",\"url\":\"https:\/\/bahiaeconomica.com.br\/wp\/\",\"name\":\"Bahia Economica\",\"description\":\"O maior portal de Economia da Bahia\",\"publisher\":{\"@id\":\"https:\/\/bahiaeconomica.com.br\/wp\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/bahiaeconomica.com.br\/wp\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/bahiaeconomica.com.br\/wp\/#organization\",\"name\":\"Bahia Econ\u00f4mica\",\"url\":\"https:\/\/bahiaeconomica.com.br\/wp\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/bahiaeconomica.com.br\/wp\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/bahiaeconomica.com.br\/wp\/wp-content\/uploads\/2020\/12\/cropped-BE.png\",\"contentUrl\":\"https:\/\/bahiaeconomica.com.br\/wp\/wp-content\/uploads\/2020\/12\/cropped-BE.png\",\"width\":512,\"height\":512,\"caption\":\"Bahia Econ\u00f4mica\"},\"image\":{\"@id\":\"https:\/\/bahiaeconomica.com.br\/wp\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/bahiaeconomica\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/bahiaeconomica.com.br\/wp\/#\/schema\/person\/b719ce0fb1c09f3c7a00d9243ced4a6f\",\"name\":\"VICTORIA ISABEL\",\"sameAs\":[\"http:\/\/www.bahiaeconomica.com.br\"],\"url\":\"https:\/\/bahiaeconomica.com.br\/wp\/author\/victoria-isabel\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"GOVERNO DO BRASIL REGULAMENTA POL\u00cdTICA NACIONAL DE CUIDADOS - Bahia Economica","description":"O maior portal de Economia da Bahia Sa\u00fade \/ Educa\u00e7\u00e3o Bahia Economica Nesta quinta-feira (24.07) foi publicado o Decreto n\u00ba 12.562, que regulamenta","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/bahiaeconomica.com.br\/wp\/2025\/07\/24\/governo-do-brasil-regulamenta-politica-nacional-de-cuidados\/","og_locale":"pt_BR","og_type":"article","og_title":"GOVERNO DO BRASIL REGULAMENTA POL\u00cdTICA NACIONAL DE CUIDADOS - Bahia Economica","og_description":"O maior portal de Economia da Bahia Sa\u00fade \/ Educa\u00e7\u00e3o Bahia Economica Nesta quinta-feira (24.07) foi publicado o Decreto n\u00ba 12.562, que regulamenta","og_url":"https:\/\/bahiaeconomica.com.br\/wp\/2025\/07\/24\/governo-do-brasil-regulamenta-politica-nacional-de-cuidados\/","og_site_name":"Bahia Economica","article_publisher":"https:\/\/www.facebook.com\/bahiaeconomica","article_published_time":"2025-07-24T20:25:11+00:00","article_modified_time":"2025-07-24T19:42:03+00:00","og_image":[{"width":768,"height":512,"url":"https:\/\/bahiaeconomica.com.br\/wp\/wp-content\/uploads\/2025\/07\/handler-5.jpg","type":"image\/jpeg"}],"author":"VICTORIA ISABEL","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"VICTORIA ISABEL","Est. tempo de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/bahiaeconomica.com.br\/wp\/2025\/07\/24\/governo-do-brasil-regulamenta-politica-nacional-de-cuidados\/#article","isPartOf":{"@id":"https:\/\/bahiaeconomica.com.br\/wp\/2025\/07\/24\/governo-do-brasil-regulamenta-politica-nacional-de-cuidados\/"},"author":{"name":"VICTORIA ISABEL","@id":"https:\/\/bahiaeconomica.com.br\/wp\/#\/schema\/person\/b719ce0fb1c09f3c7a00d9243ced4a6f"},"headline":"GOVERNO DO BRASIL REGULAMENTA POL\u00cdTICA NACIONAL DE CUIDADOS","datePublished":"2025-07-24T20:25:11+00:00","dateModified":"2025-07-24T19:42:03+00:00","mainEntityOfPage":{"@id":"https:\/\/bahiaeconomica.com.br\/wp\/2025\/07\/24\/governo-do-brasil-regulamenta-politica-nacional-de-cuidados\/"},"wordCount":573,"publisher":{"@id":"https:\/\/bahiaeconomica.com.br\/wp\/#organization"},"keywords":["Pol\u00edtica Nacional de Cuidados"],"articleSection":["Sa\u00fade \/ Educa\u00e7\u00e3o"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/bahiaeconomica.com.br\/wp\/2025\/07\/24\/governo-do-brasil-regulamenta-politica-nacional-de-cuidados\/","url":"https:\/\/bahiaeconomica.com.br\/wp\/2025\/07\/24\/governo-do-brasil-regulamenta-politica-nacional-de-cuidados\/","name":"GOVERNO DO BRASIL REGULAMENTA POL\u00cdTICA NACIONAL DE CUIDADOS - Bahia Economica","isPartOf":{"@id":"https:\/\/bahiaeconomica.com.br\/wp\/#website"},"datePublished":"2025-07-24T20:25:11+00:00","dateModified":"2025-07-24T19:42:03+00:00","description":"O maior portal de Economia da Bahia Sa\u00fade \/ Educa\u00e7\u00e3o Bahia Economica Nesta quinta-feira (24.07) foi publicado o Decreto n\u00ba 12.562, que regulamenta","breadcrumb":{"@id":"https:\/\/bahiaeconomica.com.br\/wp\/2025\/07\/24\/governo-do-brasil-regulamenta-politica-nacional-de-cuidados\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/bahiaeconomica.com.br\/wp\/2025\/07\/24\/governo-do-brasil-regulamenta-politica-nacional-de-cuidados\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/bahiaeconomica.com.br\/wp\/2025\/07\/24\/governo-do-brasil-regulamenta-politica-nacional-de-cuidados\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/bahiaeconomica.com.br\/wp\/"},{"@type":"ListItem","position":2,"name":"GOVERNO DO BRASIL REGULAMENTA POL\u00cdTICA NACIONAL DE CUIDADOS"}]},{"@type":"WebSite","@id":"https:\/\/bahiaeconomica.com.br\/wp\/#website","url":"https:\/\/bahiaeconomica.com.br\/wp\/","name":"Bahia Economica","description":"O maior portal de Economia da Bahia","publisher":{"@id":"https:\/\/bahiaeconomica.com.br\/wp\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/bahiaeconomica.com.br\/wp\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/bahiaeconomica.com.br\/wp\/#organization","name":"Bahia Econ\u00f4mica","url":"https:\/\/bahiaeconomica.com.br\/wp\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/bahiaeconomica.com.br\/wp\/#\/schema\/logo\/image\/","url":"https:\/\/bahiaeconomica.com.br\/wp\/wp-content\/uploads\/2020\/12\/cropped-BE.png","contentUrl":"https:\/\/bahiaeconomica.com.br\/wp\/wp-content\/uploads\/2020\/12\/cropped-BE.png","width":512,"height":512,"caption":"Bahia Econ\u00f4mica"},"image":{"@id":"https:\/\/bahiaeconomica.com.br\/wp\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/bahiaeconomica"]},{"@type":"Person","@id":"https:\/\/bahiaeconomica.com.br\/wp\/#\/schema\/person\/b719ce0fb1c09f3c7a00d9243ced4a6f","name":"VICTORIA ISABEL","sameAs":["http:\/\/www.bahiaeconomica.com.br"],"url":"https:\/\/bahiaeconomica.com.br\/wp\/author\/victoria-isabel\/"}]}},"views":5,"_links":{"self":[{"href":"https:\/\/bahiaeconomica.com.br\/wp\/wp-json\/wp\/v2\/posts\/920501"}],"collection":[{"href":"https:\/\/bahiaeconomica.com.br\/wp\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bahiaeconomica.com.br\/wp\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bahiaeconomica.com.br\/wp\/wp-json\/wp\/v2\/users\/15"}],"replies":[{"embeddable":true,"href":"https:\/\/bahiaeconomica.com.br\/wp\/wp-json\/wp\/v2\/comments?post=920501"}],"version-history":[{"count":1,"href":"https:\/\/bahiaeconomica.com.br\/wp\/wp-json\/wp\/v2\/posts\/920501\/revisions"}],"predecessor-version":[{"id":920506,"href":"https:\/\/bahiaeconomica.com.br\/wp\/wp-json\/wp\/v2\/posts\/920501\/revisions\/920506"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bahiaeconomica.com.br\/wp\/wp-json\/wp\/v2\/media\/920505"}],"wp:attachment":[{"href":"https:\/\/bahiaeconomica.com.br\/wp\/wp-json\/wp\/v2\/media?parent=920501"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bahiaeconomica.com.br\/wp\/wp-json\/wp\/v2\/categories?post=920501"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bahiaeconomica.com.br\/wp\/wp-json\/wp\/v2\/tags?post=920501"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}