{"id":905636,"date":"2025-05-23T19:31:18","date_gmt":"2025-05-23T22:31:18","guid":{"rendered":"https:\/\/bahiaeconomica.com.br\/wp\/?p=905636"},"modified":"2025-05-23T19:01:45","modified_gmt":"2025-05-23T22:01:45","slug":"governo-da-bahia-conclui-novas-obras-de-contencao-de-encostas-no-interior-do-estado","status":"publish","type":"post","link":"https:\/\/bahiaeconomica.com.br\/wp\/2025\/05\/23\/governo-da-bahia-conclui-novas-obras-de-contencao-de-encostas-no-interior-do-estado\/","title":{"rendered":"GOVERNO DA BAHIA CONCLUI NOVAS OBRAS DE CONTEN\u00c7\u00c3O DE ENCOSTAS NO INTERIOR DO ESTADO"},"content":{"rendered":"<p>Mais duas importantes obras de conten\u00e7\u00e3o de encostas foram conclu\u00eddas pelo Governo do Estado da Bahia, por meio da Companhia de Desenvolvimento Urbano do Estado da Bahia (Conder), desta vez nos munic\u00edpios de Jaguaquara e Concei\u00e7\u00e3o do Almeida. Com essas entregas, j\u00e1 s\u00e3o 19 conten\u00e7\u00f5es de encostas realizadas em dez munic\u00edpios no interior do estado, somando investimentos de R$ 52,7 milh\u00f5es. As interven\u00e7\u00f5es fazem parte de um conjunto de a\u00e7\u00f5es estrat\u00e9gicas para garantir mais seguran\u00e7a \u00e0 popula\u00e7\u00e3o que vive em \u00e1reas de risco, demonstrando que a atua\u00e7\u00e3o da Conder ultrapassa as fronteiras da capital.<\/p>\n<p>No munic\u00edpio de Concei\u00e7\u00e3o do Almeida, na Rua S\u00e3o Francisco, foram mais de 4,3 mil m\u00b2 de solo grampeado, com 68,56 m\u00b3 de cortina atirantada, al\u00e9m de um amplo sistema de drenagem e recupera\u00e7\u00e3o vegetal de mais de 500 m\u00b2. J\u00e1 em Jaguaquara, a conten\u00e7\u00e3o foi executada na BR-420, com 3,4 mil m\u00b2 de solo grampeado, drenagem com valetas, canaletas e gabi\u00f5es, al\u00e9m de hidrossemeadura para prote\u00e7\u00e3o vegetal. Juntas, as interven\u00e7\u00f5es contaram com um investimento de R$ 6,6 milh\u00f5es, beneficiando diretamente 2,3 mil pessoas.<\/p>\n<p>Para Adriana Luz, coordenadora de Preven\u00e7\u00e3o \u00e0 Desastres Naturais da Conder, o trabalho realizado para estabiliza\u00e7\u00e3o de encostas na cidade de Salvador e em outros munic\u00edpios da Bahia, j\u00e1 vem apresentando importantes resultados. &#8220;O volume de chuvas previsto para todo o m\u00eas de maio aconteceu apenas na primeira semana do m\u00eas, e as \u00e1reas de risco n\u00e3o apresentaram maiores danos ou fatos relevantes de deslizamentos ou fatalidades. \u00c9 com esse \u00e2nimo que continuamos trabalhando para aprovar e licitar as 65 obras selecionadas pelo Novo PAC e estamos empenhados para que muitas dessas obras sejam iniciadas ainda este ano&#8221;, afirmou Adriana.<\/p>\n<p>A dona de casa, Valdelice Ribeiro, de Concei\u00e7\u00e3o do Almeida, aprovou a obra da conten\u00e7\u00e3o de encosta em sua rua. &#8220;Antes era um verdadeiro caos, com mato e esgoto a c\u00e9u aberto. Mas agora, gra\u00e7as ao trabalho realizado, a encosta est\u00e1 linda e segura. \u00c9 um verdadeiro presente para a nossa comunidade&#8221;, afirmou Valdelice.<\/p>\n<p>Atualmente, outras seis obras est\u00e3o em andamento no interior, nos munic\u00edpios de Mutu\u00edpe (3 conten\u00e7\u00f5es de encostas), e Gandu, Itabuna e Teol\u00e2ndia, com uma interven\u00e7\u00e3o cada. H\u00e1 ainda uma obra prestes a ser iniciada em Piritiba e 20 em fase de licita\u00e7\u00e3o, contemplando cidades como Ilh\u00e9us, Itacar\u00e9, Camacan, Medeiros Neto e Nova Cana\u00e3. Ao todo, entre obras conclu\u00eddas, em execu\u00e7\u00e3o ou previstas, s\u00e3o 46 interven\u00e7\u00f5es desse tipo no interior da Bahia, com um investimento previsto de aproximadamente R$ 132 milh\u00f5es. O conjunto dessas obras beneficiar\u00e1 mais de 42 mil pessoas diretamente.<\/p>\n<p>Foto: Conder<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mais duas importantes obras de conten\u00e7\u00e3o de encostas foram conclu\u00eddas pelo Governo do Estado da Bahia, por meio da Companhia de Desenvolvimento Urbano do Estado da Bahia (Conder), desta vez nos munic\u00edpios de Jaguaquara e Concei\u00e7\u00e3o do Almeida. Com essas entregas, j\u00e1 s\u00e3o 19 conten\u00e7\u00f5es de encostas realizadas em dez munic\u00edpios no interior do estado, [&hellip;]<\/p>\n","protected":false},"author":16,"featured_media":905640,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[5],"tags":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v20.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>GOVERNO DA BAHIA CONCLUI NOVAS OBRAS DE CONTEN\u00c7\u00c3O DE ENCOSTAS NO INTERIOR DO ESTADO - Bahia Economica<\/title>\n<meta name=\"description\" content=\"O maior portal de Economia da Bahia MUNIC\u00cdPIOS Bahia Economica\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/bahiaeconomica.com.br\/wp\/2025\/05\/23\/governo-da-bahia-conclui-novas-obras-de-contencao-de-encostas-no-interior-do-estado\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"GOVERNO DA BAHIA CONCLUI NOVAS OBRAS DE CONTEN\u00c7\u00c3O DE ENCOSTAS NO INTERIOR DO ESTADO - Bahia Economica\" \/>\n<meta property=\"og:description\" content=\"O maior portal de Economia da Bahia MUNIC\u00cdPIOS Bahia Economica\" \/>\n<meta property=\"og:url\" content=\"https:\/\/bahiaeconomica.com.br\/wp\/2025\/05\/23\/governo-da-bahia-conclui-novas-obras-de-contencao-de-encostas-no-interior-do-estado\/\" \/>\n<meta property=\"og:site_name\" content=\"Bahia Economica\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/bahiaeconomica\" \/>\n<meta property=\"article:published_time\" content=\"2025-05-23T22:31:18+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-05-23T22:01:45+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/bahiaeconomica.com.br\/wp\/wp-content\/uploads\/2025\/05\/08294254-5a19-4e62-b0c3-ba3ca5e2512a.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"808\" \/>\n\t<meta property=\"og:image:height\" content=\"532\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"LUIZA NASCIMENTO\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"LUIZA NASCIMENTO\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/bahiaeconomica.com.br\/wp\/2025\/05\/23\/governo-da-bahia-conclui-novas-obras-de-contencao-de-encostas-no-interior-do-estado\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/bahiaeconomica.com.br\/wp\/2025\/05\/23\/governo-da-bahia-conclui-novas-obras-de-contencao-de-encostas-no-interior-do-estado\/\"},\"author\":{\"name\":\"LUIZA NASCIMENTO\",\"@id\":\"https:\/\/bahiaeconomica.com.br\/wp\/#\/schema\/person\/18273ac0fe04bfd4e7b101bf17d40152\"},\"headline\":\"GOVERNO DA BAHIA CONCLUI NOVAS OBRAS DE CONTEN\u00c7\u00c3O DE ENCOSTAS NO INTERIOR DO ESTADO\",\"datePublished\":\"2025-05-23T22:31:18+00:00\",\"dateModified\":\"2025-05-23T22:01:45+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/bahiaeconomica.com.br\/wp\/2025\/05\/23\/governo-da-bahia-conclui-novas-obras-de-contencao-de-encostas-no-interior-do-estado\/\"},\"wordCount\":470,\"publisher\":{\"@id\":\"https:\/\/bahiaeconomica.com.br\/wp\/#organization\"},\"articleSection\":[\"MUNIC\u00cdPIOS\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/bahiaeconomica.com.br\/wp\/2025\/05\/23\/governo-da-bahia-conclui-novas-obras-de-contencao-de-encostas-no-interior-do-estado\/\",\"url\":\"https:\/\/bahiaeconomica.com.br\/wp\/2025\/05\/23\/governo-da-bahia-conclui-novas-obras-de-contencao-de-encostas-no-interior-do-estado\/\",\"name\":\"GOVERNO DA BAHIA CONCLUI NOVAS OBRAS DE CONTEN\u00c7\u00c3O DE ENCOSTAS NO INTERIOR DO ESTADO - Bahia Economica\",\"isPartOf\":{\"@id\":\"https:\/\/bahiaeconomica.com.br\/wp\/#website\"},\"datePublished\":\"2025-05-23T22:31:18+00:00\",\"dateModified\":\"2025-05-23T22:01:45+00:00\",\"description\":\"O maior portal de Economia da Bahia MUNIC\u00cdPIOS Bahia Economica\",\"breadcrumb\":{\"@id\":\"https:\/\/bahiaeconomica.com.br\/wp\/2025\/05\/23\/governo-da-bahia-conclui-novas-obras-de-contencao-de-encostas-no-interior-do-estado\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/bahiaeconomica.com.br\/wp\/2025\/05\/23\/governo-da-bahia-conclui-novas-obras-de-contencao-de-encostas-no-interior-do-estado\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/bahiaeconomica.com.br\/wp\/2025\/05\/23\/governo-da-bahia-conclui-novas-obras-de-contencao-de-encostas-no-interior-do-estado\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/bahiaeconomica.com.br\/wp\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"GOVERNO DA BAHIA CONCLUI NOVAS OBRAS DE CONTEN\u00c7\u00c3O DE ENCOSTAS NO INTERIOR DO ESTADO\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/bahiaeconomica.com.br\/wp\/#website\",\"url\":\"https:\/\/bahiaeconomica.com.br\/wp\/\",\"name\":\"Bahia Economica\",\"description\":\"O maior portal de Economia da Bahia\",\"publisher\":{\"@id\":\"https:\/\/bahiaeconomica.com.br\/wp\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/bahiaeconomica.com.br\/wp\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/bahiaeconomica.com.br\/wp\/#organization\",\"name\":\"Bahia Econ\u00f4mica\",\"url\":\"https:\/\/bahiaeconomica.com.br\/wp\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/bahiaeconomica.com.br\/wp\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/bahiaeconomica.com.br\/wp\/wp-content\/uploads\/2020\/12\/cropped-BE.png\",\"contentUrl\":\"https:\/\/bahiaeconomica.com.br\/wp\/wp-content\/uploads\/2020\/12\/cropped-BE.png\",\"width\":512,\"height\":512,\"caption\":\"Bahia Econ\u00f4mica\"},\"image\":{\"@id\":\"https:\/\/bahiaeconomica.com.br\/wp\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/bahiaeconomica\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/bahiaeconomica.com.br\/wp\/#\/schema\/person\/18273ac0fe04bfd4e7b101bf17d40152\",\"name\":\"LUIZA NASCIMENTO\",\"sameAs\":[\"http:\/\/www.bahiaeconomica.com.br\"],\"url\":\"https:\/\/bahiaeconomica.com.br\/wp\/author\/luiza-nascimento\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"GOVERNO DA BAHIA CONCLUI NOVAS OBRAS DE CONTEN\u00c7\u00c3O DE ENCOSTAS NO INTERIOR DO ESTADO - Bahia Economica","description":"O maior portal de Economia da Bahia MUNIC\u00cdPIOS Bahia Economica","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/bahiaeconomica.com.br\/wp\/2025\/05\/23\/governo-da-bahia-conclui-novas-obras-de-contencao-de-encostas-no-interior-do-estado\/","og_locale":"pt_BR","og_type":"article","og_title":"GOVERNO DA BAHIA CONCLUI NOVAS OBRAS DE CONTEN\u00c7\u00c3O DE ENCOSTAS NO INTERIOR DO ESTADO - Bahia Economica","og_description":"O maior portal de Economia da Bahia MUNIC\u00cdPIOS Bahia Economica","og_url":"https:\/\/bahiaeconomica.com.br\/wp\/2025\/05\/23\/governo-da-bahia-conclui-novas-obras-de-contencao-de-encostas-no-interior-do-estado\/","og_site_name":"Bahia Economica","article_publisher":"https:\/\/www.facebook.com\/bahiaeconomica","article_published_time":"2025-05-23T22:31:18+00:00","article_modified_time":"2025-05-23T22:01:45+00:00","og_image":[{"width":808,"height":532,"url":"https:\/\/bahiaeconomica.com.br\/wp\/wp-content\/uploads\/2025\/05\/08294254-5a19-4e62-b0c3-ba3ca5e2512a.jpg","type":"image\/jpeg"}],"author":"LUIZA NASCIMENTO","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"LUIZA NASCIMENTO","Est. tempo de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/bahiaeconomica.com.br\/wp\/2025\/05\/23\/governo-da-bahia-conclui-novas-obras-de-contencao-de-encostas-no-interior-do-estado\/#article","isPartOf":{"@id":"https:\/\/bahiaeconomica.com.br\/wp\/2025\/05\/23\/governo-da-bahia-conclui-novas-obras-de-contencao-de-encostas-no-interior-do-estado\/"},"author":{"name":"LUIZA NASCIMENTO","@id":"https:\/\/bahiaeconomica.com.br\/wp\/#\/schema\/person\/18273ac0fe04bfd4e7b101bf17d40152"},"headline":"GOVERNO DA BAHIA CONCLUI NOVAS OBRAS DE CONTEN\u00c7\u00c3O DE ENCOSTAS NO INTERIOR DO ESTADO","datePublished":"2025-05-23T22:31:18+00:00","dateModified":"2025-05-23T22:01:45+00:00","mainEntityOfPage":{"@id":"https:\/\/bahiaeconomica.com.br\/wp\/2025\/05\/23\/governo-da-bahia-conclui-novas-obras-de-contencao-de-encostas-no-interior-do-estado\/"},"wordCount":470,"publisher":{"@id":"https:\/\/bahiaeconomica.com.br\/wp\/#organization"},"articleSection":["MUNIC\u00cdPIOS"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/bahiaeconomica.com.br\/wp\/2025\/05\/23\/governo-da-bahia-conclui-novas-obras-de-contencao-de-encostas-no-interior-do-estado\/","url":"https:\/\/bahiaeconomica.com.br\/wp\/2025\/05\/23\/governo-da-bahia-conclui-novas-obras-de-contencao-de-encostas-no-interior-do-estado\/","name":"GOVERNO DA BAHIA CONCLUI NOVAS OBRAS DE CONTEN\u00c7\u00c3O DE ENCOSTAS NO INTERIOR DO ESTADO - Bahia Economica","isPartOf":{"@id":"https:\/\/bahiaeconomica.com.br\/wp\/#website"},"datePublished":"2025-05-23T22:31:18+00:00","dateModified":"2025-05-23T22:01:45+00:00","description":"O maior portal de Economia da Bahia MUNIC\u00cdPIOS Bahia Economica","breadcrumb":{"@id":"https:\/\/bahiaeconomica.com.br\/wp\/2025\/05\/23\/governo-da-bahia-conclui-novas-obras-de-contencao-de-encostas-no-interior-do-estado\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/bahiaeconomica.com.br\/wp\/2025\/05\/23\/governo-da-bahia-conclui-novas-obras-de-contencao-de-encostas-no-interior-do-estado\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/bahiaeconomica.com.br\/wp\/2025\/05\/23\/governo-da-bahia-conclui-novas-obras-de-contencao-de-encostas-no-interior-do-estado\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/bahiaeconomica.com.br\/wp\/"},{"@type":"ListItem","position":2,"name":"GOVERNO DA BAHIA CONCLUI NOVAS OBRAS DE CONTEN\u00c7\u00c3O DE ENCOSTAS NO INTERIOR DO ESTADO"}]},{"@type":"WebSite","@id":"https:\/\/bahiaeconomica.com.br\/wp\/#website","url":"https:\/\/bahiaeconomica.com.br\/wp\/","name":"Bahia Economica","description":"O maior portal de Economia da Bahia","publisher":{"@id":"https:\/\/bahiaeconomica.com.br\/wp\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/bahiaeconomica.com.br\/wp\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/bahiaeconomica.com.br\/wp\/#organization","name":"Bahia Econ\u00f4mica","url":"https:\/\/bahiaeconomica.com.br\/wp\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/bahiaeconomica.com.br\/wp\/#\/schema\/logo\/image\/","url":"https:\/\/bahiaeconomica.com.br\/wp\/wp-content\/uploads\/2020\/12\/cropped-BE.png","contentUrl":"https:\/\/bahiaeconomica.com.br\/wp\/wp-content\/uploads\/2020\/12\/cropped-BE.png","width":512,"height":512,"caption":"Bahia Econ\u00f4mica"},"image":{"@id":"https:\/\/bahiaeconomica.com.br\/wp\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/bahiaeconomica"]},{"@type":"Person","@id":"https:\/\/bahiaeconomica.com.br\/wp\/#\/schema\/person\/18273ac0fe04bfd4e7b101bf17d40152","name":"LUIZA NASCIMENTO","sameAs":["http:\/\/www.bahiaeconomica.com.br"],"url":"https:\/\/bahiaeconomica.com.br\/wp\/author\/luiza-nascimento\/"}]}},"views":6,"_links":{"self":[{"href":"https:\/\/bahiaeconomica.com.br\/wp\/wp-json\/wp\/v2\/posts\/905636"}],"collection":[{"href":"https:\/\/bahiaeconomica.com.br\/wp\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bahiaeconomica.com.br\/wp\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bahiaeconomica.com.br\/wp\/wp-json\/wp\/v2\/users\/16"}],"replies":[{"embeddable":true,"href":"https:\/\/bahiaeconomica.com.br\/wp\/wp-json\/wp\/v2\/comments?post=905636"}],"version-history":[{"count":1,"href":"https:\/\/bahiaeconomica.com.br\/wp\/wp-json\/wp\/v2\/posts\/905636\/revisions"}],"predecessor-version":[{"id":905641,"href":"https:\/\/bahiaeconomica.com.br\/wp\/wp-json\/wp\/v2\/posts\/905636\/revisions\/905641"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bahiaeconomica.com.br\/wp\/wp-json\/wp\/v2\/media\/905640"}],"wp:attachment":[{"href":"https:\/\/bahiaeconomica.com.br\/wp\/wp-json\/wp\/v2\/media?parent=905636"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bahiaeconomica.com.br\/wp\/wp-json\/wp\/v2\/categories?post=905636"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bahiaeconomica.com.br\/wp\/wp-json\/wp\/v2\/tags?post=905636"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}