{"id":705225,"date":"2022-12-10T15:00:57","date_gmt":"2022-12-10T18:00:57","guid":{"rendered":"https:\/\/bahiaeconomica.com.br\/wp\/beta\/?p=705225"},"modified":"2022-12-10T14:48:51","modified_gmt":"2022-12-10T17:48:51","slug":"novos-ministros-de-lula-chegam-com-desafios","status":"publish","type":"post","link":"https:\/\/bahiaeconomica.com.br\/wp\/2022\/12\/10\/novos-ministros-de-lula-chegam-com-desafios\/","title":{"rendered":"NOVOS MINISTROS DE LULA CHEGAM COM DESAFIOS"},"content":{"rendered":"\n<p>Anunciados pelo presidente eleito Luiz In\u00e1cio Lula da Silva (PT) nesta sexta-feira, os futuros ministros da Defesa, Jos\u00e9 M\u00facio, e da Justi\u00e7a, Fl\u00e1vio Dino (PSB), ter\u00e3o como desafio despolitizar e reposicionar as For\u00e7as Armadas e as pol\u00edcias, n\u00facleos centrais do governo de Jair Bolsonaro (PL). <\/p>\n\n\n\n<!--more-->\n\n\n\n<p>No caso de M\u00facio, uma das tarefas ser\u00e1 contornar insatisfa\u00e7\u00f5es com a perda de espa\u00e7o dos militares no Executivo, enquanto Dino ter\u00e1 a atribui\u00e7\u00e3o de liderar o desmonte da legisla\u00e7\u00e3o armamentista implementada nos \u00faltimos quatro anos.<\/p>\n\n\n\n<p>Ex-ministro do Tribunal de Contas da Uni\u00e3o, M\u00facio foi escolhido para a Defesa, o minist\u00e9rio considerado o mais sens\u00edvel do in\u00edcio do governo Lula, justamente por sua capacidade de interlocu\u00e7\u00e3o \u2014 ele tem tr\u00e2nsito com petistas, com bolsonaristas e com militares. Em sua carreira pol\u00edtica, foi cinco vezes eleito deputado federal por Pernambuco, a maior parte do tempo no PTB, mas com passagens tamb\u00e9m por PSDB e o extinto PFL.<\/p>\n\n\n\n<p>Ministro das Rela\u00e7\u00f5es Institucionais no segundo governo do petista, M\u00facio recebeu justamente de Lula a indica\u00e7\u00e3o para sua cadeira no TCU. No tribunal, agradou o presidente Jair Bolsonaro: durante um evento com a participa\u00e7\u00e3o do presidente da Rep\u00fablica, ficou famosa a declara\u00e7\u00e3o de Bolsonaro ao dizer que era &#8220;apaixonado&#8221; por M\u00facio, numa defer\u00eancia ao ent\u00e3o ministro do TCU.<\/p>\n\n\n\n<p>Respons\u00e1vel agora pela interlocu\u00e7\u00e3o com as For\u00e7as Armadas, M\u00facio ter\u00e1 como um de seus principais desafios apaziguar e despolitizar os militares, \u201cpartidarizados\u201d por Bolsonaro. Durante o atual governo, manifesta\u00e7\u00f5es pol\u00edticas dos militares da ativa passaram a ser corriqueiras, \u00e0 margem das regras da caserna. Al\u00e9m disso, ter\u00e1 que encontrar uma sa\u00edda para os atos nas portas dos quart\u00e9is, com manifestantes que t\u00eam contestado o resultado eleitoral.<\/p>\n\n\n\n<p>M\u00facio ter\u00e1 ainda a miss\u00e3o de conduzir a rela\u00e7\u00e3o com as For\u00e7as durante investiga\u00e7\u00f5es e puni\u00e7\u00f5es de eventuais crimes cometidos por militares ao contestar o processo eleitoral. Em entrevista \u00e0 GloboNews nesta sexta, ele afirmou que n\u00e3o ser\u00e3o toleradas manifesta\u00e7\u00f5es pol\u00edticas de militares nas redes sociais, mas n\u00e3o detalhou quais provid\u00eancias ser\u00e3o tomadas, limitando-se a dizer que agir\u00e1 com &#8220;do\u00e7ura&#8221;. Com eventuais cortes or\u00e7ament\u00e1rios que podem amea\u00e7ar programas militares, tamb\u00e9m ser\u00e1 preciso lidar com poss\u00edveis insatisfa\u00e7\u00f5es nas For\u00e7as Armadas.<\/p>\n\n\n\n<p>J\u00e1 Fl\u00e1vio Dino, \u00e0 Frente da Justi\u00e7a e Seguran\u00e7a P\u00fablica, ter\u00e1 como miss\u00e3o primeira a despolitiza\u00e7\u00e3o das pol\u00edcias sob seu comando, especialmente a Pol\u00edcia Rodovi\u00e1ria Federal, que deu mais sinais de proximidade e atua\u00e7\u00e3o pol\u00edtica a favor do atual governo. Outro desafio ser\u00e1 garantir autonomia e independ\u00eancia das investiga\u00e7\u00f5es da Pol\u00edcia Federal \u2014 na transi\u00e7\u00e3o, os trabalhos de seu grupo apontaram para o aparelhamento da PF sob Bolsonaro.<\/p>\n\n\n\n<p>Tamb\u00e9m foi dada a ele a atribui\u00e7\u00e3o de liderar o processo de desmonte da legisla\u00e7\u00e3o armamentista implementada por Bolsonaro. Na GloboNews, Dino disse n\u00e3o ver sentido em \u201c termos hoje mais armas em m\u00e3os privadas do que nas pol\u00edcias militares no Brasil\u201d, e prometeu rever o atual cen\u00e1rio, com foco no porte de armas pesadas, como fuzis.<\/p>\n\n\n\n<p>Ap\u00f3s os atritos de Bolsonaro especialmente com o STF e o TSE, Dino tamb\u00e9m ter\u00e1 papel decisivo na reconstru\u00e7\u00e3o das rela\u00e7\u00f5es institucionais do Executivo, em especial com o Judici\u00e1rio. Juiz federal de carreira, ele chegou a presidir a associa\u00e7\u00e3o nacional da categoria e foi secret\u00e1rio-geral do Conselho Nacional de Justi\u00e7a (CNJ).<\/p>\n\n\n\n<p>Com in\u00edcio na pol\u00edtica pelo PCdoB, Dino foi presidente da Embratur no governo de Dilma Rousseff (PT) e depois se elegeu duas vezes governador do Maranh\u00e3o, derrotando candidatos apoiados pelo cl\u00e3 Sarney. Em seu governo, montou um dos maiores arcos de alian\u00e7as partid\u00e1rias do pa\u00eds. No ano passado, sob articula\u00e7\u00e3o de Lula, se filiou ao PSB, e agora \u00e9 o primeiro ministro de uma sigla aliada a ser confirmado no governo. Eleito senador em outubro e, indo para o governo, dar\u00e1 vaga a Ana Paula Lobato (PDT) no Senado.<\/p>\n\n\n\n<p>Foto: Ag\u00eancia O Globo e AFP<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Anunciados pelo presidente eleito Luiz In\u00e1cio Lula da Silva (PT) nesta sexta-feira, os futuros ministros da Defesa, Jos\u00e9 M\u00facio, e da Justi\u00e7a, Fl\u00e1vio Dino (PSB), ter\u00e3o como desafio despolitizar e reposicionar as For\u00e7as Armadas e as pol\u00edcias, n\u00facleos centrais do governo de Jair Bolsonaro (PL).<\/p>\n","protected":false},"author":1,"featured_media":705226,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[14,3],"tags":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v20.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>NOVOS MINISTROS DE LULA CHEGAM COM DESAFIOS - Bahia Economica<\/title>\n<meta name=\"description\" content=\"O maior portal de Economia da Bahia DESTAQUE DO DIA, ECONOMIA \/ POL\u00cdTICA Bahia Economica\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/bahiaeconomica.com.br\/wp\/2022\/12\/10\/novos-ministros-de-lula-chegam-com-desafios\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"NOVOS MINISTROS DE LULA CHEGAM COM DESAFIOS - Bahia Economica\" \/>\n<meta property=\"og:description\" content=\"O maior portal de Economia da Bahia DESTAQUE DO DIA, ECONOMIA \/ POL\u00cdTICA Bahia Economica\" \/>\n<meta property=\"og:url\" content=\"https:\/\/bahiaeconomica.com.br\/wp\/2022\/12\/10\/novos-ministros-de-lula-chegam-com-desafios\/\" \/>\n<meta property=\"og:site_name\" content=\"Bahia Economica\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/bahiaeconomica\" \/>\n<meta property=\"article:published_time\" content=\"2022-12-10T18:00:57+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-12-10T17:48:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/bahiaeconomica.com.br\/wp\/wp-content\/uploads\/2022\/12\/arte-1-.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"924\" \/>\n\t<meta property=\"og:image:height\" content=\"552\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/bahiaeconomica.com.br\/wp\/2022\/12\/10\/novos-ministros-de-lula-chegam-com-desafios\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/bahiaeconomica.com.br\/wp\/2022\/12\/10\/novos-ministros-de-lula-chegam-com-desafios\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\/\/bahiaeconomica.com.br\/wp\/#\/schema\/person\/cb1ab5ba96ad3d9390805381c76284ec\"},\"headline\":\"NOVOS MINISTROS DE LULA CHEGAM COM DESAFIOS\",\"datePublished\":\"2022-12-10T18:00:57+00:00\",\"dateModified\":\"2022-12-10T17:48:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/bahiaeconomica.com.br\/wp\/2022\/12\/10\/novos-ministros-de-lula-chegam-com-desafios\/\"},\"wordCount\":725,\"publisher\":{\"@id\":\"https:\/\/bahiaeconomica.com.br\/wp\/#organization\"},\"articleSection\":[\"DESTAQUE DO DIA\",\"ECONOMIA \/ POL\u00cdTICA\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/bahiaeconomica.com.br\/wp\/2022\/12\/10\/novos-ministros-de-lula-chegam-com-desafios\/\",\"url\":\"https:\/\/bahiaeconomica.com.br\/wp\/2022\/12\/10\/novos-ministros-de-lula-chegam-com-desafios\/\",\"name\":\"NOVOS MINISTROS DE LULA CHEGAM COM DESAFIOS - Bahia Economica\",\"isPartOf\":{\"@id\":\"https:\/\/bahiaeconomica.com.br\/wp\/#website\"},\"datePublished\":\"2022-12-10T18:00:57+00:00\",\"dateModified\":\"2022-12-10T17:48:51+00:00\",\"description\":\"O maior portal de Economia da Bahia DESTAQUE DO DIA, ECONOMIA \/ POL\u00cdTICA Bahia Economica\",\"breadcrumb\":{\"@id\":\"https:\/\/bahiaeconomica.com.br\/wp\/2022\/12\/10\/novos-ministros-de-lula-chegam-com-desafios\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/bahiaeconomica.com.br\/wp\/2022\/12\/10\/novos-ministros-de-lula-chegam-com-desafios\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/bahiaeconomica.com.br\/wp\/2022\/12\/10\/novos-ministros-de-lula-chegam-com-desafios\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/bahiaeconomica.com.br\/wp\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"NOVOS MINISTROS DE LULA CHEGAM COM DESAFIOS\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/bahiaeconomica.com.br\/wp\/#website\",\"url\":\"https:\/\/bahiaeconomica.com.br\/wp\/\",\"name\":\"Bahia Economica\",\"description\":\"O maior portal de Economia da Bahia\",\"publisher\":{\"@id\":\"https:\/\/bahiaeconomica.com.br\/wp\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/bahiaeconomica.com.br\/wp\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/bahiaeconomica.com.br\/wp\/#organization\",\"name\":\"Bahia Econ\u00f4mica\",\"url\":\"https:\/\/bahiaeconomica.com.br\/wp\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/bahiaeconomica.com.br\/wp\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/bahiaeconomica.com.br\/wp\/wp-content\/uploads\/2020\/12\/cropped-BE.png\",\"contentUrl\":\"https:\/\/bahiaeconomica.com.br\/wp\/wp-content\/uploads\/2020\/12\/cropped-BE.png\",\"width\":512,\"height\":512,\"caption\":\"Bahia Econ\u00f4mica\"},\"image\":{\"@id\":\"https:\/\/bahiaeconomica.com.br\/wp\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/bahiaeconomica\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/bahiaeconomica.com.br\/wp\/#\/schema\/person\/cb1ab5ba96ad3d9390805381c76284ec\",\"name\":\"admin\",\"url\":\"https:\/\/bahiaeconomica.com.br\/wp\/author\/admin\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"NOVOS MINISTROS DE LULA CHEGAM COM DESAFIOS - Bahia Economica","description":"O maior portal de Economia da Bahia DESTAQUE DO DIA, ECONOMIA \/ POL\u00cdTICA Bahia Economica","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/bahiaeconomica.com.br\/wp\/2022\/12\/10\/novos-ministros-de-lula-chegam-com-desafios\/","og_locale":"pt_BR","og_type":"article","og_title":"NOVOS MINISTROS DE LULA CHEGAM COM DESAFIOS - Bahia Economica","og_description":"O maior portal de Economia da Bahia DESTAQUE DO DIA, ECONOMIA \/ POL\u00cdTICA Bahia Economica","og_url":"https:\/\/bahiaeconomica.com.br\/wp\/2022\/12\/10\/novos-ministros-de-lula-chegam-com-desafios\/","og_site_name":"Bahia Economica","article_publisher":"https:\/\/www.facebook.com\/bahiaeconomica","article_published_time":"2022-12-10T18:00:57+00:00","article_modified_time":"2022-12-10T17:48:51+00:00","og_image":[{"width":924,"height":552,"url":"https:\/\/bahiaeconomica.com.br\/wp\/wp-content\/uploads\/2022\/12\/arte-1-.webp","type":"image\/webp"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"admin","Est. tempo de leitura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/bahiaeconomica.com.br\/wp\/2022\/12\/10\/novos-ministros-de-lula-chegam-com-desafios\/#article","isPartOf":{"@id":"https:\/\/bahiaeconomica.com.br\/wp\/2022\/12\/10\/novos-ministros-de-lula-chegam-com-desafios\/"},"author":{"name":"admin","@id":"https:\/\/bahiaeconomica.com.br\/wp\/#\/schema\/person\/cb1ab5ba96ad3d9390805381c76284ec"},"headline":"NOVOS MINISTROS DE LULA CHEGAM COM DESAFIOS","datePublished":"2022-12-10T18:00:57+00:00","dateModified":"2022-12-10T17:48:51+00:00","mainEntityOfPage":{"@id":"https:\/\/bahiaeconomica.com.br\/wp\/2022\/12\/10\/novos-ministros-de-lula-chegam-com-desafios\/"},"wordCount":725,"publisher":{"@id":"https:\/\/bahiaeconomica.com.br\/wp\/#organization"},"articleSection":["DESTAQUE DO DIA","ECONOMIA \/ POL\u00cdTICA"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/bahiaeconomica.com.br\/wp\/2022\/12\/10\/novos-ministros-de-lula-chegam-com-desafios\/","url":"https:\/\/bahiaeconomica.com.br\/wp\/2022\/12\/10\/novos-ministros-de-lula-chegam-com-desafios\/","name":"NOVOS MINISTROS DE LULA CHEGAM COM DESAFIOS - Bahia Economica","isPartOf":{"@id":"https:\/\/bahiaeconomica.com.br\/wp\/#website"},"datePublished":"2022-12-10T18:00:57+00:00","dateModified":"2022-12-10T17:48:51+00:00","description":"O maior portal de Economia da Bahia DESTAQUE DO DIA, ECONOMIA \/ POL\u00cdTICA Bahia Economica","breadcrumb":{"@id":"https:\/\/bahiaeconomica.com.br\/wp\/2022\/12\/10\/novos-ministros-de-lula-chegam-com-desafios\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/bahiaeconomica.com.br\/wp\/2022\/12\/10\/novos-ministros-de-lula-chegam-com-desafios\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/bahiaeconomica.com.br\/wp\/2022\/12\/10\/novos-ministros-de-lula-chegam-com-desafios\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/bahiaeconomica.com.br\/wp\/"},{"@type":"ListItem","position":2,"name":"NOVOS MINISTROS DE LULA CHEGAM COM DESAFIOS"}]},{"@type":"WebSite","@id":"https:\/\/bahiaeconomica.com.br\/wp\/#website","url":"https:\/\/bahiaeconomica.com.br\/wp\/","name":"Bahia Economica","description":"O maior portal de Economia da Bahia","publisher":{"@id":"https:\/\/bahiaeconomica.com.br\/wp\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/bahiaeconomica.com.br\/wp\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/bahiaeconomica.com.br\/wp\/#organization","name":"Bahia Econ\u00f4mica","url":"https:\/\/bahiaeconomica.com.br\/wp\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/bahiaeconomica.com.br\/wp\/#\/schema\/logo\/image\/","url":"https:\/\/bahiaeconomica.com.br\/wp\/wp-content\/uploads\/2020\/12\/cropped-BE.png","contentUrl":"https:\/\/bahiaeconomica.com.br\/wp\/wp-content\/uploads\/2020\/12\/cropped-BE.png","width":512,"height":512,"caption":"Bahia Econ\u00f4mica"},"image":{"@id":"https:\/\/bahiaeconomica.com.br\/wp\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/bahiaeconomica"]},{"@type":"Person","@id":"https:\/\/bahiaeconomica.com.br\/wp\/#\/schema\/person\/cb1ab5ba96ad3d9390805381c76284ec","name":"admin","url":"https:\/\/bahiaeconomica.com.br\/wp\/author\/admin\/"}]}},"views":2,"_links":{"self":[{"href":"https:\/\/bahiaeconomica.com.br\/wp\/wp-json\/wp\/v2\/posts\/705225"}],"collection":[{"href":"https:\/\/bahiaeconomica.com.br\/wp\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bahiaeconomica.com.br\/wp\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bahiaeconomica.com.br\/wp\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/bahiaeconomica.com.br\/wp\/wp-json\/wp\/v2\/comments?post=705225"}],"version-history":[{"count":1,"href":"https:\/\/bahiaeconomica.com.br\/wp\/wp-json\/wp\/v2\/posts\/705225\/revisions"}],"predecessor-version":[{"id":705227,"href":"https:\/\/bahiaeconomica.com.br\/wp\/wp-json\/wp\/v2\/posts\/705225\/revisions\/705227"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bahiaeconomica.com.br\/wp\/wp-json\/wp\/v2\/media\/705226"}],"wp:attachment":[{"href":"https:\/\/bahiaeconomica.com.br\/wp\/wp-json\/wp\/v2\/media?parent=705225"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bahiaeconomica.com.br\/wp\/wp-json\/wp\/v2\/categories?post=705225"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bahiaeconomica.com.br\/wp\/wp-json\/wp\/v2\/tags?post=705225"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}